{"id":1,"date":"2022-12-14T10:46:00","date_gmt":"2022-12-14T10:46:00","guid":{"rendered":"http:\/\/newswawe.weplayagency.com\/?p=1"},"modified":"2026-02-24T14:03:32","modified_gmt":"2026-02-24T14:03:32","slug":"tests-dintrusion-les-resultats-de-swawe","status":"publish","type":"post","link":"https:\/\/swawe.fr\/en\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/","title":{"rendered":"Intrusion tests, SWAWE results"},"content":{"rendered":"\n\n\n[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<h1 class=\"entry-title\">Tests d\u2019intrusion, les r\u00e9sultats de SWAWE<\/h1>\n<p>SWAWE a \u00e9t\u00e9 malmen\u00e9 par les \u00e9quipes de la soci\u00e9t\u00e9 INTRINSEC qui ont r\u00e9alis\u00e9 un audit de vuln\u00e9rabilit\u00e9 de notre plateforme h\u00e9berg\u00e9e chez OVH.<\/p>\n<p class=\"p1\">Nous avons volontairement laiss\u00e9 \u00ab\u00a0ouvert\u00a0\u00bb cet environnement pour que les faiblesses remont\u00e9es suite aux tests d\u2019intrusions soient les plus pertinentes possible.<\/p>\n<p class=\"p1\">L\u2019objectif de ce test \u00e9tait notamment de v\u00e9rifier qu\u2019un attaquant n\u2019est pas en mesure d\u2019acc\u00e9der \u00e0 des fonctionnalit\u00e9s critiques pouvant impacter les syst\u00e8mes de nos clients.<\/p>\n<p class=\"p1\">Voici donc les r\u00e9sultats obtenus\u00a0:<\/p>\n<p class=\"p1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/12\/SWAWE-Note-audit-3-1080x215-1.png\" width=\"1080\" height=\"215\" alt=\"\" class=\"wp-image-1195 aligncenter size-full\" srcset=\"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/12\/SWAWE-Note-audit-3-1080x215-1.png 1080w, https:\/\/swawe.fr\/wp-content\/uploads\/2022\/12\/SWAWE-Note-audit-3-1080x215-1-980x195.png 980w, https:\/\/swawe.fr\/wp-content\/uploads\/2022\/12\/SWAWE-Note-audit-3-1080x215-1-480x96.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1080px, 100vw\" \/><\/p>\n<p><!-- \/divi:paragraph --><\/p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<h2>Qualification <span style=\"color: #993300;\">r\u00e9seau<\/span><\/h2>\n<p>\u2714\ufe0f Le trafic en HTTP sur le port 80 st redirig\u00e9 en HTTPS sur le port 403<\/p>\n<h2>Qualification <span style=\"color: #993300;\">syst\u00e8me<\/span><\/h2>\n<p>\u2714\ufe0f La configuration de diff\u00e9rentes couches cryptographiques est correcte<\/p>\n<h2>Qualification <span style=\"color: #993300;\">applicative<\/span><\/h2>\n<p>\u2714\ufe0f La gestion des autorisations aux diff\u00e9rentes sections de l&rsquo;application est bonne<\/p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/swawe.fr\/wp-content\/uploads\/2022\/12\/cheks-s.jpeg\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb title_text=\u00a0\u00bbcheks-s\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<p>Nous mettons tout en \u0153uvre pour am\u00e9liorer cette note avec les recommandations si dessous correspondant aux vuln\u00e9rabilit\u00e9s trouv\u00e9es\u00a0:<\/p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/swawe.fr\/wp-content\/uploads\/2022\/12\/test-intrusion-.png\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb title_text=\u00a0\u00bbtest intrusion\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\n\n","protected":false},"excerpt":{"rendered":"<p>Tests d\u2019intrusion, les r\u00e9sultats de SWAWE SWAWE a \u00e9t\u00e9 malmen\u00e9 par les \u00e9quipes de la soci\u00e9t\u00e9 INTRINSEC qui ont r\u00e9alis\u00e9 un audit de vuln\u00e9rabilit\u00e9 de notre plateforme h\u00e9berg\u00e9e chez OVH. Nous avons volontairement laiss\u00e9 \u00ab\u00a0ouvert\u00a0\u00bb cet environnement pour que les faiblesses remont\u00e9es suite aux tests d\u2019intrusions soient les plus pertinentes possible. L\u2019objectif de ce test [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p>Welcome to WordPress. This is your first post. Edit or delete it, then start writing!<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gouvernance-risques-conformite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tests d\u2019intrusion, les r\u00e9sultats de SWAWE - Swawe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swawe.fr\/en\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE - Swawe\" \/>\n<meta property=\"og:description\" content=\"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE SWAWE a \u00e9t\u00e9 malmen\u00e9 par les \u00e9quipes de la soci\u00e9t\u00e9 INTRINSEC qui ont r\u00e9alis\u00e9 un audit de vuln\u00e9rabilit\u00e9 de notre plateforme h\u00e9berg\u00e9e chez OVH. Nous avons volontairement laiss\u00e9 \u00ab\u00a0ouvert\u00a0\u00bb cet environnement pour que les faiblesses remont\u00e9es suite aux tests d\u2019intrusions soient les plus pertinentes possible. L\u2019objectif de ce test [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swawe.fr\/en\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/\" \/>\n<meta property=\"og:site_name\" content=\"Swawe\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T10:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T14:03:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/09\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Geoffrey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Geoffrey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/\"},\"author\":{\"name\":\"Geoffrey\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/#\\\/schema\\\/person\\\/952252dc4280d444b93cbbff800a296a\"},\"headline\":\"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE\",\"datePublished\":\"2022-12-14T10:46:00+00:00\",\"dateModified\":\"2026-02-24T14:03:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/\"},\"wordCount\":375,\"image\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swawe.fr\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg\",\"articleSection\":[\"Gouvernance Risques Conformit\u00e9 (GRC)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/\",\"url\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/\",\"name\":\"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE - Swawe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swawe.fr\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg\",\"datePublished\":\"2022-12-14T10:46:00+00:00\",\"dateModified\":\"2026-02-24T14:03:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/#\\\/schema\\\/person\\\/952252dc4280d444b93cbbff800a296a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swawe.fr\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/swawe.fr\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg\",\"width\":2560,\"height\":1747},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/gouvernance-risques-conformite\\\/tests-dintrusion-les-resultats-de-swawe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/swawe.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/#website\",\"url\":\"https:\\\/\\\/swawe.fr\\\/\",\"name\":\"Swawe\",\"description\":\"Your Compliance Companion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swawe.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/#\\\/schema\\\/person\\\/952252dc4280d444b93cbbff800a296a\",\"name\":\"Geoffrey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/991790badc95025b7878c7f1bc7c0d96c824cfe0c012292dd83771d7411931d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/991790badc95025b7878c7f1bc7c0d96c824cfe0c012292dd83771d7411931d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/991790badc95025b7878c7f1bc7c0d96c824cfe0c012292dd83771d7411931d2?s=96&d=mm&r=g\",\"caption\":\"Geoffrey\"},\"url\":\"https:\\\/\\\/swawe.fr\\\/en\\\/author\\\/geoffrey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE - Swawe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swawe.fr\/en\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/","og_locale":"en_US","og_type":"article","og_title":"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE - Swawe","og_description":"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE SWAWE a \u00e9t\u00e9 malmen\u00e9 par les \u00e9quipes de la soci\u00e9t\u00e9 INTRINSEC qui ont r\u00e9alis\u00e9 un audit de vuln\u00e9rabilit\u00e9 de notre plateforme h\u00e9berg\u00e9e chez OVH. Nous avons volontairement laiss\u00e9 \u00ab\u00a0ouvert\u00a0\u00bb cet environnement pour que les faiblesses remont\u00e9es suite aux tests d\u2019intrusions soient les plus pertinentes possible. L\u2019objectif de ce test [&hellip;]","og_url":"https:\/\/swawe.fr\/en\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/","og_site_name":"Swawe","article_published_time":"2022-12-14T10:46:00+00:00","article_modified_time":"2026-02-24T14:03:32+00:00","og_image":[{"width":2560,"height":1747,"url":"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/09\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Geoffrey","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Geoffrey","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/#article","isPartOf":{"@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/"},"author":{"name":"Geoffrey","@id":"https:\/\/swawe.fr\/#\/schema\/person\/952252dc4280d444b93cbbff800a296a"},"headline":"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE","datePublished":"2022-12-14T10:46:00+00:00","dateModified":"2026-02-24T14:03:32+00:00","mainEntityOfPage":{"@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/"},"wordCount":375,"image":{"@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/#primaryimage"},"thumbnailUrl":"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/09\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg","articleSection":["Gouvernance Risques Conformit\u00e9 (GRC)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/","url":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/","name":"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE - Swawe","isPartOf":{"@id":"https:\/\/swawe.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/#primaryimage"},"image":{"@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/#primaryimage"},"thumbnailUrl":"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/09\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg","datePublished":"2022-12-14T10:46:00+00:00","dateModified":"2026-02-24T14:03:32+00:00","author":{"@id":"https:\/\/swawe.fr\/#\/schema\/person\/952252dc4280d444b93cbbff800a296a"},"breadcrumb":{"@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/#primaryimage","url":"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/09\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg","contentUrl":"https:\/\/swawe.fr\/wp-content\/uploads\/2022\/09\/christian-velitchkov-oCD1HUJmFIM-unsplash-scaled.jpg","width":2560,"height":1747},{"@type":"BreadcrumbList","@id":"https:\/\/swawe.fr\/gouvernance-risques-conformite\/tests-dintrusion-les-resultats-de-swawe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swawe.fr\/"},{"@type":"ListItem","position":2,"name":"Tests d\u2019intrusion, les r\u00e9sultats de SWAWE"}]},{"@type":"WebSite","@id":"https:\/\/swawe.fr\/#website","url":"https:\/\/swawe.fr\/","name":"Swawe","description":"Your Compliance Companion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swawe.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/swawe.fr\/#\/schema\/person\/952252dc4280d444b93cbbff800a296a","name":"Geoffrey","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/991790badc95025b7878c7f1bc7c0d96c824cfe0c012292dd83771d7411931d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/991790badc95025b7878c7f1bc7c0d96c824cfe0c012292dd83771d7411931d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/991790badc95025b7878c7f1bc7c0d96c824cfe0c012292dd83771d7411931d2?s=96&d=mm&r=g","caption":"Geoffrey"},"url":"https:\/\/swawe.fr\/en\/author\/geoffrey\/"}]}},"_links":{"self":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":8,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":2277,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/posts\/1\/revisions\/2277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/media\/1201"}],"wp:attachment":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}