{"id":3,"date":"2022-09-16T06:46:43","date_gmt":"2022-09-16T06:46:43","guid":{"rendered":"http:\/\/newswawe.weplayagency.com\/?page_id=3"},"modified":"2022-12-05T10:19:29","modified_gmt":"2022-12-05T10:19:29","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/swawe.fr\/en\/politique-de-confidentialite\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.18.0&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div class=\"et_pb_row et_pb_row_1\">\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_1  et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h2>Politique de confidentialit\u00e9 et de protection des donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es sur le site swawe.fr<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_row et_pb_row_2\">\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_2  et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_2  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p>Bienvenue sur ce site, dont SECUREWAY (SARL au capital de 105000 euros, dont le si\u00e8ge social est situ\u00e9 8 avenue de Paris \u00e0 Versailles \u2013 78000) est le propri\u00e9taire et responsable du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.<br \/>SECUREWAY, qui est depuis 14 ans un acteur incontournable dans le domaine de la s\u00e9curit\u00e9 applicative SAP \u00ae, est une entreprise engag\u00e9e dans la protection de votre vie priv\u00e9e et de vos donn\u00e9es personnelles. Cette note d\u2019information a pour objectif de vous expliquer comment nous, SECUREWAY, collectons, utilisons et communiquons les informations que vous nous fournissez via notre site institutionnel, les sites de nos produits et services, nos portails d\u00e9di\u00e9s et applications mobiles. Merci de bien vouloir la lire enti\u00e8rement avant d\u2019utiliser ce site ou de nous transmettre des informations vous concernant.<br \/>Nous prenons les dispositions n\u00e9cessaires afin d\u2019assurer un niveau de s\u00e9curit\u00e9 de vos donn\u00e9es personnelles, en lien et en conformit\u00e9 avec la loi n\u00b078-17 du 6 janvier 1978, dite \u00ab Informatique et Libert\u00e9s \u00bb et la nouvelle r\u00e9glementation europ\u00e9enne, le RGPD (R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es n\u00b02016\/79 du 27 avril 2016), applicable depuis le 25 mai 2018.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_3  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>A quel moment collectons-nous vos donn\u00e9es personnelles ?<\/h3>\n<p>Vous pouvez naviguer sur une grande partie de notre site sans fournir de donn\u00e9es \u00e0 caract\u00e8re personnel.\u00a0 Toutefois vous serez amen\u00e9s \u00e0 nous confier des donn\u00e9es \u00e0 caract\u00e8re personnel si vous souhaitez nous contacter via notre formulaire dans la section \u2018contact\u2019 de notre site.<\/p>\n<p>Les champs \u00e0 renseigner dans le formulaire de Contact de notre site sont n\u00e9cessaires afin de r\u00e9pondre \u00e0 votre demande. Si ces champs ne sont pas compl\u00e9t\u00e9s, nous ne pourrons pas vous contacter.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_4  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Quelles sont les donn\u00e9es personnelles que nous collectons\u00a0?<\/h3>\n<p>Nous collectons et traitons notamment vos nom, pr\u00e9nom, adresse, adresse email, num\u00e9ro de t\u00e9l\u00e9phone, civilit\u00e9, soci\u00e9t\u00e9, fonction.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_5  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Comment utiliserons-nous vos donn\u00e9es personnelles\u00a0?<\/h3>\n<p>Nous utiliserons vos donn\u00e9es personnelles pour un ou plusieurs objectifs suivants :<\/p>\n<ul>\n<li>pour l\u2019am\u00e9lioration de nos produits et services en vous invitant \u00e0 participer \u00e0 des sondages, des \u00e9tudes, des enqu\u00eates de satisfaction et des tests produits ;<\/li>\n<li>pour l\u2019am\u00e9lioration de votre exp\u00e9rience utilisateur sur notre site et pour b\u00e9n\u00e9ficier des fonctionnalit\u00e9s et services du site ;<\/li>\n<li>pour l\u2019analyse et l\u2019\u00e9tablissement de statistiques relatives \u00e0 la consultation et \u00e0 l\u2019utilisation du site (nombre de pages vues, nombre de visites et activit\u00e9) de nos services (articles lus) ;<\/li>\n<li>pour l\u2019envoi d\u2019informations et de newsletters personnalis\u00e9es sur nos produits et services et leur \u00e9volution, sur notre actualit\u00e9 ;<\/li>\n<li>pour la gestion des demandes de droit d\u2019acc\u00e8s, de rectification et d\u2019opposition.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_6  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Comment g\u00e9rer vos donn\u00e9es personnelles\u00a0?<\/h3>\n<p>Si vous ne souhaitez plus recevoir de communications de notre part, veuillez utiliser le lien Se D\u00e9sabonner pour ne plus recevoir de nos nouvelles \u00e0 l\u2019avenir.<\/p>\n<p>Vous pouvez \u00e9galement contacter le r\u00e9f\u00e9rent RGPD par courriel\u00a0:<span>\u00a0<\/span><span class=\"unselectable\">rgpd@secureway.fr<\/span><span>\u00a0<\/span>(voir article 8).<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_7  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Qui seront les destinataires de vos donn\u00e9es personnelles\u00a0?<\/h3>\n<p>SECUREWAY reste le seul destinataire de vos donn\u00e9es personnelles.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_8  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>O\u00f9 sont stock\u00e9es vos donn\u00e9es personnelles et sont-elles en s\u00e9curit\u00e9\u00a0?<\/h3>\n<p>Vos donn\u00e9es personnelles sont stock\u00e9es dans nos bases de donn\u00e9es.<br \/>Nous attachons une grande importance \u00e0 la s\u00e9curit\u00e9 de vos donn\u00e9es. C\u2019est la raison pour laquelle nous mettons en \u0153uvre toutes les mesures appropri\u00e9es pour emp\u00eacher dans la mesure du possible toute alt\u00e9ration ou perte de vos donn\u00e9es ou tout acc\u00e8s non autoris\u00e9 \u00e0 celles-ci.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_9  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Vos donn\u00e9es personnelles seront-elles transf\u00e9r\u00e9es hors de l\u2019Union Europ\u00e9enne\u00a0?<\/h3>\n<p>Non.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_10  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Quels sont vos droits concernant vos donn\u00e9es personnelles\u00a0?<\/h3>\n<p>Vous disposez d\u2019un droit d\u2019acc\u00e8s, de rectification et d\u2019effacement des donn\u00e9es personnelles vous concernant, ainsi que d\u2019un droit \u00e0 la limitation du traitement et \u00e0 la portabilit\u00e9 de vos donn\u00e9es. Vous disposez \u00e9galement du droit d\u2019opposition pour motif l\u00e9gitime au traitement de vos donn\u00e9es personnelles ainsi que du droit d\u2019opposition au traitement de vos donn\u00e9es \u00e0 des fins de prospection. Vous disposez enfin du droit d\u2019introduire une r\u00e9clamation aupr\u00e8s de la CNIL.<\/p>\n<p>Vous pouvez exercer ses droits \u00e0 tout moment en vous adressant \u00e0 notre service client :<\/p>\n<ul>\n<li>Par courrier postal : SECUREWAY \u2013 8 avenue de Paris \u2013 78000 VERSAILLES<\/li>\n<li>Par courriel :<span>\u00a0<\/span><span class=\"unselectable\">rgpd@secureway.fr<\/span><\/li>\n<\/ul>\n<p>Derni\u00e8re pr\u00e9cision : toute demande par courrier postal ou courriel devra \u00eatre sign\u00e9e et accompagn\u00e9e de la photocopie d\u2019un titre d\u2019identit\u00e9 portant votre signature et pr\u00e9ciser l\u2019adresse \u00e0 laquelle devra vous parvenir la r\u00e9ponse. Une r\u00e9ponse vous sera alors adress\u00e9e dans un d\u00e9lai d\u2019un \u00e0 trois mois suivant la r\u00e9ception de la demande.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_11  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Quelle est la dur\u00e9e de conservation de vos donn\u00e9es personnelles\u00a0?<\/h3>\n<p>Vos donn\u00e9es personnelles sont conserv\u00e9es pendant une dur\u00e9e qui n\u2019exc\u00e8de pas la dur\u00e9e n\u00e9cessaire aux finalit\u00e9s pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_12  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h3>Liens hypertextes \u00ab cookies \u00bb et balise (\u2018tag\u2019) internet<\/h3>\n<p>Le site https:\/\/swawe.fr\/ contient un certain nombre de liens hypertextes vers d\u2019autres sites, mis en place avec l\u2019autorisation de SECUREWAY. Cependant, SECUREWAY n\u2019a pas la possibilit\u00e9 de v\u00e9rifier le contenu des sites ainsi visit\u00e9s, et n\u2019assumera en cons\u00e9quence aucune responsabilit\u00e9 de ce fait.<\/p>\n<p>Sauf si vous d\u00e9cidez de d\u00e9sactiver les cookies, vous acceptez que le site puisse les utiliser. Vous pouvez \u00e0 tout moment d\u00e9sactiver ces cookies et ce gratuitement \u00e0 partir des possibilit\u00e9s de d\u00e9sactivation qui vous sont offertes et rappel\u00e9es ci-apr\u00e8s, sachant que cela peut r\u00e9duire ou emp\u00eacher l\u2019accessibilit\u00e9 \u00e0 tout ou partie des Services propos\u00e9s par le site.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_13  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h4>Cookies<\/h4>\n<p>Un \u00ab cookie \u00bb est un petit fichier d\u2019information envoy\u00e9 sur le navigateur de l\u2019Utilisateur et enregistr\u00e9 au sein du terminal de l\u2019Utilisateur (ex : ordinateur, smartphone), (ci-apr\u00e8s \u00ab Cookies \u00bb). Ce fichier comprend des informations telles que le nom de domaine de l\u2019Utilisateur, le fournisseur d\u2019acc\u00e8s Internet de l\u2019Utilisateur, le syst\u00e8me d\u2019exploitation de l\u2019Utilisateur, ainsi que la date et l\u2019heure d\u2019acc\u00e8s. Les Cookies ne risquent en aucun cas d\u2019endommager le terminal de l\u2019Utilisateur.<\/p>\n<p>SECUREWAY est susceptible de traiter les informations de l\u2019Utilisateur concernant sa visite du Site, telles que les pages consult\u00e9es, les recherches effectu\u00e9es. Ces informations permettent \u00e0 SECUREWAY d\u2019am\u00e9liorer le contenu du Site, de la navigation de l\u2019Utilisateur.<\/p>\n<p>Les Cookies facilitant la navigation et\/ou la fourniture des services propos\u00e9s par le Site, l\u2019Utilisateur peut configurer son navigateur pour qu\u2019il lui permette de d\u00e9cider s\u2019il souhaite ou non les accepter de mani\u00e8re que des Cookies soient enregistr\u00e9s dans le terminal ou, au contraire, qu\u2019ils soient rejet\u00e9s, soit syst\u00e9matiquement, soit selon leur \u00e9metteur. L\u2019Utilisateur peut \u00e9galement configurer son logiciel de navigation de mani\u00e8re que l\u2019acceptation ou le refus des Cookies lui soient propos\u00e9s ponctuellement, avant qu\u2019un Cookie soit susceptible d\u2019\u00eatre enregistr\u00e9 dans son terminal. SECUREWAY informe l\u2019Utilisateur que, dans ce cas, il se peut que les fonctionnalit\u00e9s de son logiciel de navigation ne soient pas toutes disponibles.<\/p>\n<p>Si l\u2019Utilisateur refuse l\u2019enregistrement de Cookies dans son terminal ou son navigateur, ou si l\u2019Utilisateur supprime ceux qui y sont enregistr\u00e9s, l\u2019Utilisateur est inform\u00e9 que sa navigation et son exp\u00e9rience sur le Site peuvent \u00eatre limit\u00e9es. Cela pourrait \u00e9galement \u00eatre le cas lorsque SECUREWAY ou l\u2019un de ses prestataires ne peut pas reconna\u00eetre, \u00e0 des fins de compatibilit\u00e9 technique, le type de navigateur utilis\u00e9 par le terminal, les param\u00e8tres de langue et d\u2019affichage ou le pays depuis lequel le terminal semble connect\u00e9 \u00e0 Internet.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, SECUREWAY d\u00e9cline toute responsabilit\u00e9 pour les cons\u00e9quences li\u00e9es au fonctionnement d\u00e9grad\u00e9 du Site et des services \u00e9ventuellement propos\u00e9s par SECUREWAY, r\u00e9sultant (i) du refus de Cookies par l\u2019Utilisateur (ii) de l\u2019impossibilit\u00e9 pour SECUREWAY d\u2019enregistrer ou de consulter les Cookies n\u00e9cessaires \u00e0 leur fonctionnement du fait du choix de l\u2019Utilisateur. Pour la gestion des Cookies et des choix de l\u2019Utilisateur, la configuration de chaque navigateur est diff\u00e9rente. Elle est d\u00e9crite dans le menu d\u2019aide du navigateur, qui permettra de savoir de quelle mani\u00e8re l\u2019Utilisateur peut modifier ses souhaits en mati\u00e8re de Cookies.<\/p>\n<p>\u00c0 tout moment, l\u2019Utilisateur peut faire le choix d\u2019exprimer et de modifier ses souhaits en mati\u00e8re de Cookies. SECUREWAY pourra en outre faire appel aux services de prestataires externes pour l\u2019aider \u00e0 recueillir et traiter les informations d\u00e9crites dans cette section.<\/p>\n<p>Enfin, en cliquant sur les ic\u00f4nes d\u00e9di\u00e9es aux r\u00e9seaux sociaux figurant sur le Site https:\/\/swawe.fr\/\u00a0ou dans son application mobile et si l\u2019Utilisateur a accept\u00e9 le d\u00e9p\u00f4t de cookies en poursuivant sa navigation sur le Site Internet ou l\u2019application mobile de SECUREWAY, les r\u00e9seaux sociaux figurant sur le Site peuvent \u00e9galement d\u00e9poser des cookies sur vos terminaux (ordinateur, tablette, t\u00e9l\u00e9phone portable).<\/p>\n<p>Ces types de cookies ne sont d\u00e9pos\u00e9s sur vos terminaux qu\u2019\u00e0 condition que vous y consentiez, en continuant votre navigation sur le Site Internet ou l\u2019application mobile de SECUREWAY. \u00c0 tout moment, l\u2019Utilisateur peut n\u00e9anmoins revenir sur son consentement \u00e0 ce que le Site <a href=\"https:\/\/swawe.fr\/\">https:\/\/swawe.fr\/<\/a> d\u00e9pose ce type de cookies.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_14  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h4>Balises (\u2018TAGS\u2019) Internet<\/h4>\n<p>SECUREWAY peut employer occasionnellement des balises Internet (\u00e9galement appel\u00e9es \u00ab tags \u00bb, ou balises d\u2019action, GIF \u00e0 un pixel, GIF transparents, GIF invisibles et GIF un \u00e0 un) et les d\u00e9ployer par l\u2019interm\u00e9diaire d\u2019un partenaire sp\u00e9cialiste d\u2019analyses Web susceptible de se trouver (et donc de stocker les informations correspondantes, y compris l\u2019adresse IP de l\u2019Utilisateur) dans un pays \u00e9tranger.<\/p>\n<p>Ces balises sont plac\u00e9es \u00e0 la fois dans les publicit\u00e9s en ligne permettant aux internautes d\u2019acc\u00e9der au Site, et sur les diff\u00e9rentes pages de celui-ci.<\/p>\n<p>Cette technologie permet \u00e0 SECUREWAY d\u2019\u00e9valuer les r\u00e9ponses des visiteurs face au Site et l\u2019efficacit\u00e9 de ses actions (par exemple, le nombre de fois o\u00f9 une page est ouverte et les informations consult\u00e9es), ainsi que l\u2019utilisation de ce Site par l\u2019Utilisateur.<\/p>\n<p>Le prestataire externe pourra \u00e9ventuellement recueillir des informations sur les visiteurs du Site et d\u2019autres sites Internet gr\u00e2ce \u00e0 ces balises, constituer des rapports sur l\u2019activit\u00e9 du Site \u00e0 l\u2019attention de SECUREWAY, et fournir d\u2019autres services relatifs \u00e0 l\u2019utilisation de celui-ci et d\u2019Internet.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 et de protection des donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es sur le site swawe.fr Bienvenue sur ce site, dont SECUREWAY (SARL au capital de 105000 euros, dont le si\u00e8ge social est situ\u00e9 8 avenue de Paris \u00e0 Versailles \u2013 78000) est le propri\u00e9taire et responsable du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.SECUREWAY, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading -->\n<h2>Who we are<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>Our website address is: http:\/\/newswawe.weplayagency.com.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Comments<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>An anonymized string created from your email address (also called a hash) may be provided to the Gravatar service to see if you are using it. The Gravatar service privacy policy is available here: https:\/\/automattic.com\/privacy\/. After approval of your comment, your profile picture is visible to the public in the context of your comment.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Media<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you upload images to the website, you should avoid uploading images with embedded location data (EXIF GPS) included. Visitors to the website can download and extract any location data from images on the website.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Cookies<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you leave a comment on our site you may opt-in to saving your name, email address and website in cookies. These are for your convenience so that you do not have to fill in your details again when you leave another comment. These cookies will last for one year.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>If you visit our login page, we will set a temporary cookie to determine if your browser accepts cookies. This cookie contains no personal data and is discarded when you close your browser.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>When you log in, we will also set up several cookies to save your login information and your screen display choices. Login cookies last for two days, and screen options cookies last for a year. If you select \"Remember Me\", your login will persist for two weeks. If you log out of your account, the login cookies will be removed.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>If you edit or publish an article, an additional cookie will be saved in your browser. This cookie includes no personal data and simply indicates the post ID of the article you just edited. It expires after 1 day.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Embedded content from other websites<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>Articles on this site may include embedded content (e.g. videos, images, articles, etc.). Embedded content from other websites behaves in the exact same way as if the visitor has visited the other website.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>These websites may collect data about you, use cookies, embed additional third-party tracking, and monitor your interaction with that embedded content, including tracking your interaction with the embedded content if you have an account and are logged in to that website.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Who we share your data with<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you request a password reset, your IP address will be included in the reset email.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>How long we retain your data<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you leave a comment, the comment and its metadata are retained indefinitely. This is so we can recognize and approve any follow-up comments automatically instead of holding them in a moderation queue.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>For users that register on our website (if any), we also store the personal information they provide in their user profile. All users can see, edit, or delete their personal information at any time (except they cannot change their username). Website administrators can also see and edit that information.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>What rights you have over your data<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you have an account on this site, or have left comments, you can request to receive an exported file of the personal data we hold about you, including any data you have provided to us. You can also request that we erase any personal data we hold about you. This does not include any data we are obliged to keep for administrative, legal, or security purposes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Where your data is sent<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>Visitor comments may be checked through an automated spam detection service.<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 - Swawe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swawe.fr\/en\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - Swawe\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 et de protection des donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es sur le site swawe.fr Bienvenue sur ce site, dont SECUREWAY (SARL au capital de 105000 euros, dont le si\u00e8ge social est situ\u00e9 8 avenue de Paris \u00e0 Versailles \u2013 78000) est le propri\u00e9taire et responsable du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.SECUREWAY, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swawe.fr\/en\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Swawe\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-05T10:19:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/swawe.fr\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 - Swawe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/#website\"},\"datePublished\":\"2022-09-16T06:46:43+00:00\",\"dateModified\":\"2022-12-05T10:19:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swawe.fr\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swawe.fr\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/swawe.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swawe.fr\\\/#website\",\"url\":\"https:\\\/\\\/swawe.fr\\\/\",\"name\":\"Swawe\",\"description\":\"Your Compliance Companion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swawe.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - Swawe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swawe.fr\/en\/politique-de-confidentialite\/","og_locale":"en_US","og_type":"article","og_title":"Politique de confidentialit\u00e9 - Swawe","og_description":"Politique de confidentialit\u00e9 et de protection des donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es sur le site swawe.fr Bienvenue sur ce site, dont SECUREWAY (SARL au capital de 105000 euros, dont le si\u00e8ge social est situ\u00e9 8 avenue de Paris \u00e0 Versailles \u2013 78000) est le propri\u00e9taire et responsable du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel.SECUREWAY, [&hellip;]","og_url":"https:\/\/swawe.fr\/en\/politique-de-confidentialite\/","og_site_name":"Swawe","article_modified_time":"2022-12-05T10:19:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swawe.fr\/politique-de-confidentialite\/","url":"https:\/\/swawe.fr\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - Swawe","isPartOf":{"@id":"https:\/\/swawe.fr\/#website"},"datePublished":"2022-09-16T06:46:43+00:00","dateModified":"2022-12-05T10:19:29+00:00","breadcrumb":{"@id":"https:\/\/swawe.fr\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swawe.fr\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swawe.fr\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swawe.fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/swawe.fr\/#website","url":"https:\/\/swawe.fr\/","name":"Swawe","description":"Your Compliance Companion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swawe.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":6,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1044,"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/pages\/3\/revisions\/1044"}],"wp:attachment":[{"href":"https:\/\/swawe.fr\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}